{"id":1994,"date":"2022-01-13T11:50:39","date_gmt":"2022-01-13T10:50:39","guid":{"rendered":"https:\/\/www.peter-harms.com\/carrera-profesional\/"},"modified":"2026-04-20T13:05:57","modified_gmt":"2026-04-20T11:05:57","slug":"carrera-profesional","status":"publish","type":"page","link":"https:\/\/www.peter-harms.com\/es\/carrera-profesional\/","title":{"rendered":"Empleo y carrera profesional"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1994\" class=\"elementor elementor-1994\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec13295 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ec13295\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f7ff468\" data-id=\"f7ff468\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13ffbe1 elementor-widget elementor-widget-shortcode\" data-id=\"13ffbe1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"5997\" class=\"elementor elementor-5997\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b26060d elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b26060d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3041f3f8\" data-id=\"3041f3f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-28d3fafc\" data-id=\"28d3fafc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7543d52f elementor-nav-menu__align-center elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"7543d52f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i aria-hidden=\\&quot;true\\&quot; class=\\&quot;\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;&quot;},&quot;layout&quot;:&quot;horizontal&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-background e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-7543d52f\" class=\"elementor-nav-menu\"><li class=\"menu-item wpml-ls-slot-31 wpml-ls-item wpml-ls-item-de wpml-ls-menu-item wpml-ls-first-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-31-de\"><a href=\"https:\/\/www.peter-harms.com\/\" title=\"Cambiar a Alem\u00e1n\" aria-label=\"Cambiar a Alem\u00e1n\" class=\"elementor-item\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.peter-harms.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/de.png\"\n            alt=\"Alem\u00e1n\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n<li class=\"menu-item wpml-ls-slot-31 wpml-ls-item wpml-ls-item-en wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-31-en\"><a href=\"https:\/\/www.peter-harms.com\/en\/\" title=\"Cambiar a Ingl\u00e9s\" aria-label=\"Cambiar a Ingl\u00e9s\" class=\"elementor-item\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.peter-harms.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/en.png\"\n            alt=\"Ingl\u00e9s\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n<li class=\"menu-item wpml-ls-slot-31 wpml-ls-item wpml-ls-item-fr wpml-ls-menu-item wpml-ls-last-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-31-fr\"><a href=\"https:\/\/www.peter-harms.com\/fr\/\" title=\"Cambiar a Franc\u00e9s\" aria-label=\"Cambiar a Franc\u00e9s\" class=\"elementor-item\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.peter-harms.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/fr.png\"\n            alt=\"Franc\u00e9s\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-7543d52f\" class=\"elementor-nav-menu\"><li class=\"menu-item wpml-ls-slot-31 wpml-ls-item wpml-ls-item-de wpml-ls-menu-item wpml-ls-first-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-31-de\"><a href=\"https:\/\/www.peter-harms.com\/\" title=\"Cambiar a Alem\u00e1n\" aria-label=\"Cambiar a Alem\u00e1n\" class=\"elementor-item\" tabindex=\"-1\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.peter-harms.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/de.png\"\n            alt=\"Alem\u00e1n\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n<li class=\"menu-item wpml-ls-slot-31 wpml-ls-item wpml-ls-item-en wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-31-en\"><a href=\"https:\/\/www.peter-harms.com\/en\/\" title=\"Cambiar a Ingl\u00e9s\" aria-label=\"Cambiar a Ingl\u00e9s\" class=\"elementor-item\" tabindex=\"-1\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.peter-harms.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/en.png\"\n            alt=\"Ingl\u00e9s\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n<li class=\"menu-item wpml-ls-slot-31 wpml-ls-item wpml-ls-item-fr wpml-ls-menu-item wpml-ls-last-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-31-fr\"><a href=\"https:\/\/www.peter-harms.com\/fr\/\" title=\"Cambiar a Franc\u00e9s\" aria-label=\"Cambiar a Franc\u00e9s\" class=\"elementor-item\" tabindex=\"-1\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.peter-harms.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/fr.png\"\n            alt=\"Franc\u00e9s\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8d79d2d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d79d2d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-02a25cc\" data-id=\"02a25cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-591a69a elementor-widget elementor-widget-menu-anchor\" data-id=\"591a69a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"casa\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46c36a3 elementor-widget elementor-widget-theme-site-logo elementor-widget-image\" data-id=\"46c36a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-site-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.peter-harms.com\/es\/\">\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"140\" src=\"https:\/\/www.peter-harms.com\/wp-content\/uploads\/2021\/03\/LOGO_PETER_HARMS_RGB.png\" class=\"attachment-full size-full wp-image-611\" alt=\"Peter Harms weiss\" srcset=\"https:\/\/www.peter-harms.com\/wp-content\/uploads\/2021\/03\/LOGO_PETER_HARMS_RGB.png 600w, https:\/\/www.peter-harms.com\/wp-content\/uploads\/2021\/03\/LOGO_PETER_HARMS_RGB-300x70.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a75ca97\" data-id=\"a75ca97\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd831a7 elementor-nav-menu__align-center elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"dd831a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\\&quot; viewBox=\\&quot;0 0 448 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;_animation&quot;:&quot;none&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-background e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-dd831a7\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-7128\"><a class=\"elementor-item\">Empresa<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7129\"><a href=\"https:\/\/www.peter-harms.com\/es\/persona-de-contacto-2\/\" class=\"elementor-sub-item\">Persona de contacto<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7130\"><a href=\"https:\/\/www.peter-harms.com\/es\/carrera-profesional\/\" class=\"elementor-sub-item\">Empleo y carrera profesional<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-7121\"><a class=\"elementor-item\">Servicios<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7122\"><a href=\"https:\/\/www.peter-harms.com\/es\/transporte-maritimo\/\" class=\"elementor-sub-item\">Transporte mar\u00edtimo<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7123\"><a href=\"https:\/\/www.peter-harms.com\/es\/flete-aereo\/\" class=\"elementor-sub-item\">Flete a\u00e9reo<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7124\"><a href=\"https:\/\/www.peter-harms.com\/es\/carga-general-transporte-por-camion-transporte-multimodal\/\" class=\"elementor-sub-item\">Carga general \/ Transporte por cami\u00f3n \/ Transporte multimodal<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7125\"><a href=\"https:\/\/www.peter-harms.com\/es\/costumbres\/\" class=\"elementor-sub-item\">Aduanas<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7126\"><a href=\"https:\/\/www.peter-harms.com\/es\/transporte-de-mercancias-peligrosas-adr\/\" class=\"elementor-sub-item\">Transporte de mercanc\u00edas peligrosas<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7127\"><a href=\"https:\/\/www.peter-harms.com\/es\/waiver\/\" class=\"elementor-sub-item\">Waiver \/ BESC \/ ECTN<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-7118\"><a class=\"elementor-item\">Soluciones industriales<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7119\"><a href=\"https:\/\/www.peter-harms.com\/es\/food-logistics\/\" class=\"elementor-sub-item\">Food Logistics<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7270\"><a href=\"https:\/\/www.peter-harms.com\/es\/reciclaje\/\" class=\"elementor-sub-item\">Reciclaje<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7120\"><a href=\"https:\/\/www.peter-harms.com\/es\/transporte-de-mercancias-peligrosas-adr\/\" class=\"elementor-sub-item\">Qu\u00edmica<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-7117\"><a href=\"https:\/\/www.peter-harms.com\/es\/#preguntas\" class=\"elementor-item elementor-item-anchor\">FAQ<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-7110\"><a href=\"https:\/\/www.peter-harms.com\/es\/#contacte\" class=\"elementor-item elementor-item-anchor\">\u2709<\/a><\/li>\n<li class=\"menu-item wpml-ls-slot-34 wpml-ls-item wpml-ls-item-es wpml-ls-current-language wpml-ls-menu-item wpml-ls-last-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-has-children menu-item-wpml-ls-34-es\"><a href=\"https:\/\/www.peter-harms.com\/es\/\" aria-current=\"page\" aria-expanded=\"false\" aria-controls=\"wpml-ls-submenu-wpml-ls-34-es\" class=\"elementor-item\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.peter-harms.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/es.png\"\n            alt=\"Espa\u00f1ol\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item wpml-ls-slot-34 wpml-ls-item wpml-ls-item-de wpml-ls-menu-item wpml-ls-first-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-34-de\"><a href=\"https:\/\/www.peter-harms.com\/\" title=\"Cambiar a Alem\u00e1n\" aria-label=\"Cambiar a Alem\u00e1n\" class=\"elementor-sub-item\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.peter-harms.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/de.png\"\n            alt=\"Alem\u00e1n\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-34 wpml-ls-item wpml-ls-item-en wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-34-en\"><a href=\"https:\/\/www.peter-harms.com\/en\/\" title=\"Cambiar a Ingl\u00e9s\" aria-label=\"Cambiar a Ingl\u00e9s\" class=\"elementor-sub-item\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.peter-harms.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/en.png\"\n            alt=\"Ingl\u00e9s\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-34 wpml-ls-item wpml-ls-item-fr wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-34-fr\"><a href=\"https:\/\/www.peter-harms.com\/fr\/\" title=\"Cambiar a Franc\u00e9s\" aria-label=\"Cambiar a Franc\u00e9s\" class=\"elementor-sub-item\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.peter-harms.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/fr.png\"\n            alt=\"Franc\u00e9s\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Alternar men\u00fa\" aria-expanded=\"false\">\n\t\t\t<svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open e-font-icon-svg e-eicon-menu-bar\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M104 333H896C929 333 958 304 958 271S929 208 896 208H104C71 208 42 237 42 271S71 333 104 333ZM104 583H896C929 583 958 554 958 521S929 458 896 458H104C71 458 42 487 42 521S71 583 104 583ZM104 833H896C929 833 958 804 958 771S929 708 896 708H104C71 708 42 737 42 771S71 833 104 833Z\"><\/path><\/svg><svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close e-font-icon-svg e-eicon-close\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M742 167L500 408 258 167C246 154 233 150 217 150 196 150 179 158 167 167 154 179 150 196 150 212 150 229 154 242 171 254L408 500 167 742C138 771 138 800 167 829 196 858 225 858 254 829L496 587 738 829C750 842 767 846 783 846 800 846 817 842 829 829 842 817 846 804 846 783 846 767 842 750 829 737L588 500 833 258C863 229 863 200 833 171 804 137 775 137 742 167Z\"><\/path><\/svg>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-dd831a7\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-7128\"><a class=\"elementor-item\" tabindex=\"-1\">Empresa<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7129\"><a href=\"https:\/\/www.peter-harms.com\/es\/persona-de-contacto-2\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Persona de contacto<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7130\"><a href=\"https:\/\/www.peter-harms.com\/es\/carrera-profesional\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Empleo y carrera profesional<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-7121\"><a class=\"elementor-item\" tabindex=\"-1\">Servicios<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7122\"><a href=\"https:\/\/www.peter-harms.com\/es\/transporte-maritimo\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Transporte mar\u00edtimo<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7123\"><a href=\"https:\/\/www.peter-harms.com\/es\/flete-aereo\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Flete a\u00e9reo<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7124\"><a href=\"https:\/\/www.peter-harms.com\/es\/carga-general-transporte-por-camion-transporte-multimodal\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Carga general \/ Transporte por cami\u00f3n \/ Transporte multimodal<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7125\"><a href=\"https:\/\/www.peter-harms.com\/es\/costumbres\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Aduanas<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7126\"><a href=\"https:\/\/www.peter-harms.com\/es\/transporte-de-mercancias-peligrosas-adr\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Transporte de mercanc\u00edas peligrosas<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7127\"><a href=\"https:\/\/www.peter-harms.com\/es\/waiver\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Waiver \/ BESC \/ ECTN<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-7118\"><a class=\"elementor-item\" tabindex=\"-1\">Soluciones industriales<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7119\"><a href=\"https:\/\/www.peter-harms.com\/es\/food-logistics\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Food Logistics<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7270\"><a href=\"https:\/\/www.peter-harms.com\/es\/reciclaje\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Reciclaje<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7120\"><a href=\"https:\/\/www.peter-harms.com\/es\/transporte-de-mercancias-peligrosas-adr\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Qu\u00edmica<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-7117\"><a href=\"https:\/\/www.peter-harms.com\/es\/#preguntas\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">FAQ<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-7110\"><a href=\"https:\/\/www.peter-harms.com\/es\/#contacte\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">\u2709<\/a><\/li>\n<li class=\"menu-item wpml-ls-slot-34 wpml-ls-item wpml-ls-item-es wpml-ls-current-language wpml-ls-menu-item wpml-ls-last-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-has-children menu-item-wpml-ls-34-es\"><a href=\"https:\/\/www.peter-harms.com\/es\/\" aria-current=\"page\" aria-expanded=\"false\" aria-controls=\"wpml-ls-submenu-wpml-ls-34-es\" class=\"elementor-item\" tabindex=\"-1\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.peter-harms.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/es.png\"\n            alt=\"Espa\u00f1ol\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item wpml-ls-slot-34 wpml-ls-item wpml-ls-item-de wpml-ls-menu-item wpml-ls-first-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-34-de\"><a href=\"https:\/\/www.peter-harms.com\/\" title=\"Cambiar a Alem\u00e1n\" aria-label=\"Cambiar a Alem\u00e1n\" class=\"elementor-sub-item\" tabindex=\"-1\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.peter-harms.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/de.png\"\n            alt=\"Alem\u00e1n\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-34 wpml-ls-item wpml-ls-item-en wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-34-en\"><a href=\"https:\/\/www.peter-harms.com\/en\/\" title=\"Cambiar a Ingl\u00e9s\" aria-label=\"Cambiar a Ingl\u00e9s\" class=\"elementor-sub-item\" tabindex=\"-1\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.peter-harms.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/en.png\"\n            alt=\"Ingl\u00e9s\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-34 wpml-ls-item wpml-ls-item-fr wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-34-fr\"><a href=\"https:\/\/www.peter-harms.com\/fr\/\" title=\"Cambiar a Franc\u00e9s\" aria-label=\"Cambiar a Franc\u00e9s\" class=\"elementor-sub-item\" tabindex=\"-1\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.peter-harms.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/fr.png\"\n            alt=\"Franc\u00e9s\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f47b0f5 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f47b0f5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9e55422\" data-id=\"9e55422\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8bb2e1 elementor-widget elementor-widget-heading\" data-id=\"a8bb2e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestra actitud de trabajo\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1815433 elementor-widget elementor-widget-text-editor\" data-id=\"1815433\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Somos una empresa tradicional con una base de clientes s\u00f3lida y una fuerte retenci\u00f3n de los empleados. Estamos muy motivados para ofrecer a nuestros clientes el mejor rendimiento y un servicio superior. Es por eso que seguimos pregunt\u00e1ndonos qu\u00e9 podemos hacer a\u00fan mejor.<\/p>\n<p class=\"p1\">A nuestros empleados les gusta trabajar de forma independiente y est\u00e1n altamente calificados en su campo. No necesitamos jerarqu\u00edas estrictas. Tomamos decisiones con rapidez y con compromiso hanse\u00e1tico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-378eae2d envato-kit-141-top-0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"378eae2d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4ec5d4e9\" data-id=\"4ec5d4e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c92048b elementor-widget elementor-widget-heading\" data-id=\"4c92048b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestra actitud de trabajo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44439442 elementor-widget elementor-widget-text-editor\" data-id=\"44439442\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Somos una empresa tradicional con una base de clientes consolidada y una fuerte retenci\u00f3n de nuestros empleados. Siempre estamos motivados para ofrecer a nuestros clientes las mejores prestaciones y un servicio excepcional. Por eso mantenemos constantemente un estrecho di\u00e1logo con nuestros clientes y proveedores de servicios internacionales.<br \/><br \/>Nuestros empleados disfrutan trabajando de forma independiente y est\u00e1n altamente cualificados en su campo. Trabajamos entre todos los departamentos y la comunicaci\u00f3n directa es importante para nosotros. Tomamos decisiones r\u00e1pidamente y con compromiso hanse\u00e1tico.<\/p><p>Encontrar\u00e1 m\u00e1s informaci\u00f3n sobre las oportunidades profesionales : <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df573c2 elementor-widget elementor-widget-button\" data-id=\"df573c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.peter-harms.com\/karriere\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Sitio alem\u00e1n de carreras profesionales<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0ab78ee\" data-id=\"0ab78ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a7bc5f elementor-widget elementor-widget-image\" data-id=\"6a7bc5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.peter-harms.com\/wp-content\/uploads\/2021\/06\/DSC_1536-1024x682.jpg\" class=\"attachment-large size-large wp-image-1891\" alt=\"Peter Harms Team\" srcset=\"https:\/\/www.peter-harms.com\/wp-content\/uploads\/2021\/06\/DSC_1536-1024x682.jpg 1024w, https:\/\/www.peter-harms.com\/wp-content\/uploads\/2021\/06\/DSC_1536-300x200.jpg 300w, https:\/\/www.peter-harms.com\/wp-content\/uploads\/2021\/06\/DSC_1536-768x512.jpg 768w, https:\/\/www.peter-harms.com\/wp-content\/uploads\/2021\/06\/DSC_1536.jpg 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9e50a32 envato-kit-141-top-0 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9e50a32\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-319ce25\" data-id=\"319ce25\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9567567 elementor-widget elementor-widget-heading\" data-id=\"9567567\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Carrera profesional<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3a7f4a elementor-widget elementor-widget-text-editor\" data-id=\"f3a7f4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><b>\u00a1Buscamos refuerzos!<\/b><\/h2><p><b>\u00a1Ven a bordo! <\/b><\/p><ul><li>\u00bfLe gustar\u00eda hacer avanzar las cosas y progresar s\u00fa mismo?<\/li><li>\u00bfEst\u00e1s a punto de terminar la escuela y est\u00e1s interesado en un aprendizaje\u00a0como empleado (m\/f\/d) para servicios de expedici\u00f3n y log\u00edstica?<\/li><li>\u00bfViene de una industria diferente y ahora le gustar\u00eda unirse a nosotros con un cambio de carrera?<\/li><\/ul><p>Ya sea un trabajador calificado, un graduado escolar o un cambiador de carrera: siempre estamos contentos con el crecimiento del personal motivado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1d0d9cf\" data-id=\"1d0d9cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e21f1e elementor-widget elementor-widget-image\" data-id=\"1e21f1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.peter-harms.com\/wp-content\/uploads\/2022\/02\/Join-our-Team.jpeg\" class=\"attachment-large size-large wp-image-1933\" alt=\"Peter Harms Ausbildung\" srcset=\"https:\/\/www.peter-harms.com\/wp-content\/uploads\/2022\/02\/Join-our-Team.jpeg 640w, https:\/\/www.peter-harms.com\/wp-content\/uploads\/2022\/02\/Join-our-Team-300x200.jpeg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-97cecb7 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"97cecb7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-af729be\" data-id=\"af729be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8728d1d elementor-widget elementor-widget-image\" data-id=\"8728d1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.peter-harms.com\/wp-content\/uploads\/2021\/05\/DSC_8806-1024x682.jpg\" class=\"attachment-large size-large wp-image-1735\" alt=\"Peter Harms Ansprechpartner\" srcset=\"https:\/\/www.peter-harms.com\/wp-content\/uploads\/2021\/05\/DSC_8806-1024x682.jpg 1024w, https:\/\/www.peter-harms.com\/wp-content\/uploads\/2021\/05\/DSC_8806-300x200.jpg 300w, https:\/\/www.peter-harms.com\/wp-content\/uploads\/2021\/05\/DSC_8806-768x512.jpg 768w, https:\/\/www.peter-harms.com\/wp-content\/uploads\/2021\/05\/DSC_8806.jpg 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2ce2e22\" data-id=\"2ce2e22\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f34a7e elementor-widget elementor-widget-heading\" data-id=\"5f34a7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Profesionales con experiencia <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dde2aaf elementor-widget elementor-widget-text-editor\" data-id=\"dde2aaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">\u00bfYa ha adquirido experiencia profesional en transporte y log\u00edstica? \u00bfLe gusta pensar fuera de la caja y sentirse responsable de su \u00e1rea? \u00bfListo para evolucionar?<\/p><p class=\"p1\">Siempre necesitamos personas con experiencia. Empleados de todos niveles que se incorporen directamente son muy bienvenidos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-299dc2d elementor-widget elementor-widget-button\" data-id=\"299dc2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.peter-harms.com\/berufserfahrene\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">a las ofertas de empleo para profesionales con experiencia<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c336f32 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c336f32\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e2f8e76\" data-id=\"e2f8e76\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac001f1 elementor-widget elementor-widget-heading\" data-id=\"ac001f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aprendices<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37de649 elementor-widget elementor-widget-text-editor\" data-id=\"37de649\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">\u00bfEst\u00e1s interesado en un aprendizaje en el transporte y la log\u00edstica? \u00bfTienes afici\u00f3n por otros pa\u00edses y culturas? \u00bfEres comprometido, motivado y un jugador de equipo?<\/p><p class=\"p1\">\u00a1Entonces podr\u00edamos ser una buena pareja!<\/p><p class=\"p1\">Llevamos muchas d\u00e9cadas formando aprendices. Si todo va bien, puede esperar un trabajo seguro: muchos de nuestros empleados actuales comenzaron con nosotros como aprendices y todav\u00eda hoy forman parte del equipo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d114bd1 elementor-widget elementor-widget-button\" data-id=\"d114bd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.peter-harms.com\/azubis\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">a las oportunidades de formaci\u00f3n para los egresados de la escuela<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cad7dbd\" data-id=\"cad7dbd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12ac9ac elementor-widget elementor-widget-image\" data-id=\"12ac9ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.peter-harms.com\/wp-content\/uploads\/2022\/02\/German-male-student-with-group-of-other-students-outdoor-in-the-summer.jpeg\" class=\"attachment-large size-large wp-image-1930\" alt=\"Peter Harms Ausbildung\" srcset=\"https:\/\/www.peter-harms.com\/wp-content\/uploads\/2022\/02\/German-male-student-with-group-of-other-students-outdoor-in-the-summer.jpeg 640w, https:\/\/www.peter-harms.com\/wp-content\/uploads\/2022\/02\/German-male-student-with-group-of-other-students-outdoor-in-the-summer-300x200.jpeg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58e8e85 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58e8e85\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c2f503d\" data-id=\"c2f503d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52b6777 elementor-widget elementor-widget-image\" data-id=\"52b6777\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.peter-harms.com\/wp-content\/uploads\/2022\/02\/DSC_8806-neu-1024x682.jpg\" class=\"attachment-large size-large wp-image-1942\" alt=\"Peter Harms Team\" srcset=\"https:\/\/www.peter-harms.com\/wp-content\/uploads\/2022\/02\/DSC_8806-neu-1024x682.jpg 1024w, https:\/\/www.peter-harms.com\/wp-content\/uploads\/2022\/02\/DSC_8806-neu-300x200.jpg 300w, https:\/\/www.peter-harms.com\/wp-content\/uploads\/2022\/02\/DSC_8806-neu-768x512.jpg 768w, https:\/\/www.peter-harms.com\/wp-content\/uploads\/2022\/02\/DSC_8806-neu.jpg 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-952c5e1\" data-id=\"952c5e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ceb7af elementor-widget elementor-widget-heading\" data-id=\"4ceb7af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cambiador de carrera\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7898c55 elementor-widget elementor-widget-text-editor\" data-id=\"7898c55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">\u00bfNo ha trabajado antes en nuestra industria y ahora le gustar\u00eda dedicarse al transporte y a la log\u00edstica? Consideremos juntos qu\u00e9 talentos y experiencia puede aportar a nuestra empresa.<\/p><p class=\"p1\">La actitud correcta es m\u00e1s importante para nosotros que las calificaciones en papel: las brechas de conocimiento se puede cerrar r\u00e1pidamente con capacitaci\u00f3nes y cursos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e9e652 elementor-widget elementor-widget-button\" data-id=\"8e9e652\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.peter-harms.com\/quereinsteiger\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">a las oportunidades para los entrantes laterales<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-067a800 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"067a800\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-03ebf58\" data-id=\"03ebf58\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc74917 elementor-widget elementor-widget-shortcode\" data-id=\"bc74917\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"5759\" class=\"elementor elementor-5759\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75240c7e elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"75240c7e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4775d0f9\" data-id=\"4775d0f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66ac05f5 elementor-widget elementor-widget-image\" data-id=\"66ac05f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"140\" src=\"https:\/\/www.peter-harms.com\/wp-content\/uploads\/2021\/03\/LOGO_PETER_HARMS_RGB.png\" class=\"attachment-large size-large wp-image-1675\" alt=\"Peter Harms weiss\" srcset=\"https:\/\/www.peter-harms.com\/wp-content\/uploads\/2021\/03\/LOGO_PETER_HARMS_RGB.png 600w, https:\/\/www.peter-harms.com\/wp-content\/uploads\/2021\/03\/LOGO_PETER_HARMS_RGB-300x70.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-59b53d62\" data-id=\"59b53d62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1df876fc elementor-widget elementor-widget-text-editor\" data-id=\"1df876fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>BREMEN (sede principal)<\/strong><\/p><p><strong>Peter Harms Schiffahrts-<br \/>u. Speditionsgesellschaft mbH<\/strong><br \/>Am Dobben 18<br \/>28203 Bremen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a5a753 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8a5a753\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:office@peter-harms.com\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope-open\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 464c0 26.51-21.49 48-48 48H48c-26.51 0-48-21.49-48-48V200.724a48 48 0 0 1 18.387-37.776c24.913-19.529 45.501-35.365 164.2-121.511C199.412 29.17 232.797-.347 256 .003c23.198-.354 56.596 29.172 73.413 41.433 118.687 86.137 139.303 101.995 164.2 121.512A48 48 0 0 1 512 200.724V464zm-65.666-196.605c-2.563-3.728-7.7-4.595-11.339-1.907-22.845 16.873-55.462 40.705-105.582 77.079-16.825 12.266-50.21 41.781-73.413 41.43-23.211.344-56.559-29.143-73.413-41.43-50.114-36.37-82.734-60.204-105.582-77.079-3.639-2.688-8.776-1.821-11.339 1.907l-9.072 13.196a7.998 7.998 0 0 0 1.839 10.967c22.887 16.899 55.454 40.69 105.303 76.868 20.274 14.781 56.524 47.813 92.264 47.573 35.724.242 71.961-32.771 92.263-47.573 49.85-36.179 82.418-59.97 105.303-76.868a7.998 7.998 0 0 0 1.839-10.967l-9.071-13.196z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">office@peter-harms.com<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+49421337720\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+49 421 33772-0<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7750cc97\" data-id=\"7750cc97\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17bedbb elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"17bedbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>HAMBURG<\/b><\/p><p><b>Peter Harms Schiffahrts-<br \/>u. Speditionsgesellschaft mbH<\/b><br \/>Maxstrasse 23<br \/>22089 Hamburg<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a928c5a elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a928c5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:office@peter-harms.com\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope-open\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 464c0 26.51-21.49 48-48 48H48c-26.51 0-48-21.49-48-48V200.724a48 48 0 0 1 18.387-37.776c24.913-19.529 45.501-35.365 164.2-121.511C199.412 29.17 232.797-.347 256 .003c23.198-.354 56.596 29.172 73.413 41.433 118.687 86.137 139.303 101.995 164.2 121.512A48 48 0 0 1 512 200.724V464zm-65.666-196.605c-2.563-3.728-7.7-4.595-11.339-1.907-22.845 16.873-55.462 40.705-105.582 77.079-16.825 12.266-50.21 41.781-73.413 41.43-23.211.344-56.559-29.143-73.413-41.43-50.114-36.37-82.734-60.204-105.582-77.079-3.639-2.688-8.776-1.821-11.339 1.907l-9.072 13.196a7.998 7.998 0 0 0 1.839 10.967c22.887 16.899 55.454 40.69 105.303 76.868 20.274 14.781 56.524 47.813 92.264 47.573 35.724.242 71.961-32.771 92.263-47.573 49.85-36.179 82.418-59.97 105.303-76.868a7.998 7.998 0 0 0 1.839-10.967l-9.071-13.196z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">office@peter-harms.com<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+494060776350\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+49 40 6077635-0<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-586b94a elementor-section-height-min-height elementor-section-items-top elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"586b94a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e270de\" data-id=\"4e270de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21d19e6 elementor-hidden-mobile elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"21d19e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48c3344 elementor-nav-menu__align-center elementor-nav-menu--dropdown-mobile elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"48c3344\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-48c3344\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2483\"><a href=\"https:\/\/www.peter-harms.com\/es\/aviso-legal\/\" class=\"elementor-item\">imprimir<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2743\"><a href=\"https:\/\/www.peter-harms.com\/es\/intimidad\/\" class=\"elementor-item\">intimidad<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2744\"><a href=\"https:\/\/www.peter-harms.com\/wp-content\/uploads\/2022\/10\/DSLV-ADSp-2017-EN.pdf\" class=\"elementor-item\">ADSp<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-48c3344\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2483\"><a href=\"https:\/\/www.peter-harms.com\/es\/aviso-legal\/\" class=\"elementor-item\" tabindex=\"-1\">imprimir<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2743\"><a href=\"https:\/\/www.peter-harms.com\/es\/intimidad\/\" class=\"elementor-item\" tabindex=\"-1\">intimidad<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2744\"><a href=\"https:\/\/www.peter-harms.com\/wp-content\/uploads\/2022\/10\/DSLV-ADSp-2017-EN.pdf\" class=\"elementor-item\" tabindex=\"-1\">ADSp<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>El transporte mar\u00edtimo es tu negocio diario, \u00bfy quieres hacer algo m\u00e1s que gestionarlo? Entonces deber\u00edas conocernos. Somos una empresa transitaria consolidada especializada en la exportaci\u00f3n de carga mar\u00edtima y buscamos reforzar nuestro equipo. Con nosotros, asumir\u00e1s la responsabilidad de tus propias \u00f3rdenes de transporte, trabajar\u00e1s de forma independiente y estar\u00e1s cerca del cliente y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-1994","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/www.peter-harms.com\/es\/wp-json\/wp\/v2\/pages\/1994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.peter-harms.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.peter-harms.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.peter-harms.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.peter-harms.com\/es\/wp-json\/wp\/v2\/comments?post=1994"}],"version-history":[{"count":2,"href":"https:\/\/www.peter-harms.com\/es\/wp-json\/wp\/v2\/pages\/1994\/revisions"}],"predecessor-version":[{"id":8361,"href":"https:\/\/www.peter-harms.com\/es\/wp-json\/wp\/v2\/pages\/1994\/revisions\/8361"}],"wp:attachment":[{"href":"https:\/\/www.peter-harms.com\/es\/wp-json\/wp\/v2\/media?parent=1994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}